{"id":490,"date":"2023-11-02T23:34:43","date_gmt":"2023-11-03T04:34:43","guid":{"rendered":"https:\/\/masterclassodontologia.com.pe\/?page_id=490"},"modified":"2024-07-20T11:11:14","modified_gmt":"2024-07-20T16:11:14","slug":"cirugia-oral","status":"publish","type":"page","link":"https:\/\/masterclassodontologia.com.pe\/index.php\/cirugia-oral\/","title":{"rendered":"Cirug\u00eda Oral"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"490\" class=\"elementor elementor-490\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-410fb1a8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"410fb1a8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3db85719 elementor-invisible\" data-id=\"3db85719\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6755c114 elementor-widget elementor-widget-image\" data-id=\"6755c114\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img data-opt-id=800434153  fetchpriority=\"high\" decoding=\"async\" width=\"750\" height=\"199\" src=\"https:\/\/mluirrmr33wv.i.optimole.com\/w:750\/h:199\/q:mauto\/ig:avif\/https:\/\/masterclassodontologia.com.pe\/wp-content\/uploads\/2024\/02\/NewLogo_MC.png\" class=\"attachment-large size-large wp-image-1319\" alt=\"\" srcset=\"https:\/\/mluirrmr33wv.i.optimole.com\/w:1011\/h:268\/q:mauto\/ig:avif\/https:\/\/masterclassodontologia.com.pe\/wp-content\/uploads\/2024\/02\/NewLogo_MC.png 1011w, https:\/\/mluirrmr33wv.i.optimole.com\/w:300\/h:80\/q:mauto\/ig:avif\/https:\/\/masterclassodontologia.com.pe\/wp-content\/uploads\/2024\/02\/NewLogo_MC.png 300w, https:\/\/mluirrmr33wv.i.optimole.com\/w:768\/h:204\/q:mauto\/ig:avif\/https:\/\/masterclassodontologia.com.pe\/wp-content\/uploads\/2024\/02\/NewLogo_MC.png 768w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5a4dbff7\" data-id=\"5a4dbff7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-47d9b9f8 elementor-section-full_width elementor-reverse-tablet elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"47d9b9f8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-48ffbb30\" data-id=\"48ffbb30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48f58f45 elementor-widget-mobile__width-auto elementor-invisible elementor-widget elementor-widget-ekit-nav-menu\" data-id=\"48f58f45\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"ekit-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<nav class=\"ekit-wid-con ekit_menu_responsive_tablet\"\n\t\t\tdata-hamburger-icon=\"icon icon-menu-7\"\n\t\t\tdata-hamburger-icon-type=\"icon\"\n\t\t\tdata-responsive-breakpoint=\"1024\">\n\t\t\t            <button class=\"elementskit-menu-hamburger elementskit-menu-toggler\"  type=\"button\" aria-label=\"hamburger-icon\">\n                <i aria-hidden=\"true\" class=\"ekit-menu-icon icon icon-menu-7\"><\/i>            <\/button>\n            <div id=\"ekit-megamenu-principal\" class=\"elementskit-menu-container elementskit-menu-offcanvas-elements elementskit-navbar-nav-default ekit-nav-menu-one-page- ekit-nav-dropdown-hover\"><ul id=\"menu-principal\" class=\"elementskit-navbar-nav elementskit-menu-po-center submenu-click-on-icon\"><li id=\"menu-item-381\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-381 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/masterclassodontologia.com.pe\/\" class=\"ekit-menu-nav-link\">Inicio<\/a><\/li>\n<li id=\"menu-item-969\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-969 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"#\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Diplomados<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-854\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-854 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/endodoncia\/\" class=\" dropdown-item\">Endodoncia<\/a>\t<li id=\"menu-item-1647\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1647 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/odontopediatria\/\" class=\" dropdown-item\">Odontopediatr\u00eda<\/a>\t<li id=\"menu-item-520\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-520 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/cirugia-oral\/\" class=\" dropdown-item\">Cirug\u00eda Oral<\/a>\t<li id=\"menu-item-1700\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1700 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/implantologia-oral\/\" class=\" dropdown-item\">Implantolog\u00eda Oral<\/a>\t<li id=\"menu-item-1065\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1065 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/ortodoncia-y-ortopedia-maxilofacial\/\" class=\" dropdown-item\">Ortodoncia y Ortopedia Maxilofacial<\/a>\t<li id=\"menu-item-459\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-459 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/odontologia-estetica-y-restauradora\/\" class=\" dropdown-item\">Odontolog\u00eda Est\u00e9tica y Restauradora<\/a><\/ul>\n<\/li>\n<li id=\"menu-item-970\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-970 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"#\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Cursos<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-1702\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1702 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/curso-internacional-de-restauraciones-semidirectas-de-resinas-compuestas\/\" class=\" dropdown-item\">Restauraciones Semidirectas de Resinas Compuestas<\/a>\t<li id=\"menu-item-2101\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2101 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/actualizacion-2024-cirugia-paraendodontica\/\" class=\" dropdown-item\">Actualizaci\u00f3n Cirug\u00eda Paraendod\u00f3ntica 2024<\/a><\/ul>\n<\/li>\n<li id=\"menu-item-436\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-436 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/masterclassodontologia.com.pe\/moodle\/\" class=\"ekit-menu-nav-link\">Aula Virtual<\/a><\/li>\n<li id=\"menu-item-807\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-807 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/publicaciones\/\" class=\"ekit-menu-nav-link\">Blog<\/a><\/li>\n<\/ul><div class=\"elementskit-nav-identity-panel\"><button class=\"elementskit-menu-close elementskit-menu-toggler\" type=\"button\">X<\/button><\/div><\/div>\n\t\t\t<div class=\"elementskit-menu-overlay elementskit-menu-offcanvas-elements elementskit-menu-toggler ekit-nav-menu--overlay\"><\/div>        <\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4c63e50f\" data-id=\"4c63e50f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63922ca8 elementor-widget__width-auto elementor-widget elementor-widget-elementskit-header-search\" data-id=\"63922ca8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-header-search.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <a href=\"#ekit_modal-popup-63922ca8\" class=\"ekit_navsearch-button ekit-modal-popup\" aria-label=\"navsearch-button\">\n            <i aria-hidden=\"true\" class=\"icon icon-search11\"><\/i>        <\/a>\n        <!-- language switcher strart -->\n        <!-- xs modal -->\n        <div class=\"zoom-anim-dialog mfp-hide ekit_modal-searchPanel\" id=\"ekit_modal-popup-63922ca8\">\n            <div class=\"ekit-search-panel\">\n            <!-- Polylang search - thanks to Alain Melsens -->\n                <form role=\"search\" method=\"get\" class=\"ekit-search-group\" action=\"https:\/\/masterclassodontologia.com.pe\/\">\n                    <input type=\"search\" class=\"ekit_search-field\" aria-label=\"search-form\" placeholder=\"Search...\" value=\"\" name=\"s\">\n\t\t\t\t\t<button type=\"submit\" class=\"ekit_search-button\" aria-label=\"search-button\">\n                        <i aria-hidden=\"true\" class=\"icon icon-search11\"><\/i>                    <\/button>\n                <\/form>\n            <\/div>\n        <\/div><!-- End xs modal -->\n        <!-- end language switcher strart -->\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-250afcdd elementor-align-right elementor-hidden-mobile elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"250afcdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/api.whatsapp.com\/send\/?phone=941774399&#038;text&#038;type=phone_number&#038;app_absent=0\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cont\u00e1ctanos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e154fd0 elementor-align-right elementor-hidden-desktop elementor-widget__width-auto elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"1e154fd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47439e08 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"47439e08\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-76676901\" data-id=\"76676901\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9842aa9 elementor-widget elementor-widget-gum_heading\" data-id=\"9842aa9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"gum_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"gum-widget-title\"><h2 class=\"section-main-title size-default\">Cirug\u00eda Oral<\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39ff8086 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"39ff8086\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span>El objetivo del <strong>Diplomado<\/strong> en Cirug\u00eda Oral brinda los conocimientos y competencias para mejorar la calidad de vida de los pacientes, aliviar el dolor, restaurar la funci\u00f3n adecuada.&nbsp;<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4376b40 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4376b40\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-097e411\" data-id=\"097e411\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd13957 elementor-widget elementor-widget-text-editor\" data-id=\"cd13957\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>INICIO: 31 DE AGOSTO DEL 2024<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-36a075e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"36a075e1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5e3c406 elementor-invisible\" data-id=\"5e3c406\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93614f3 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"93614f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper-container\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-46e02ca swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-523351b swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-bbf6367 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-ab582d4 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous slide<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next slide<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab90b61 elementor-widget elementor-widget-heading\" data-id=\"ab90b61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Especialista:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-465b930 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"465b930\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img data-opt-id=1829555517  fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/mluirrmr33wv.i.optimole.com\/w:1600\/h:1067\/q:mauto\/ig:avif\/https:\/\/masterclassodontologia.com.pe\/wp-content\/uploads\/2023\/11\/doc_4.png\" title=\"doc_4\" alt=\"doc_4\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29e0480b elementor-widget elementor-widget-text-editor\" data-id=\"29e0480b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\"><strong>Dr. Wilmer Baldarrago Salas Ph.D. \ud83c\uddf5\ud83c\uddea<\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2eefdaff elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2eefdaff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cirujano Dentista, Universidad Cat\u00f3lica Santa Mar\u00eda, Arequipa - Per\u00fa.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Especialista en Cirug\u00eda Oral y Maxilofacial por la Facultad de Estomatolog\u00eda de la Universidad Cayetano Heredia \u2013 Per\u00fa.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profesor de la C\u00e1tedra de Cirug\u00eda Oral y Maxilofacial de la Facultad de Odontolog\u00eda de la Universidad Cat\u00f3lica de Santa Mar\u00eda.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cirujano Maxilofacial, asistente del departamento de Cirug\u00eda Bucal y Maxilofacial del Hospital Militar Regional Arequipa.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ex docente de la Universidad Nacional Mayor de San Marcos.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ex docente de la Universidad Nacional Peruana Cayetano Heredia.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ex docente de la Universidad Nacional Federico Villareal.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-450712fa elementor-widget elementor-widget-heading\" data-id=\"450712fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Objetivos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-194e7672 elementor-widget elementor-widget-text-editor\" data-id=\"194e7672\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nuestro Diplomado en Cirug\u00eda Oral entrega las Herramientas a quienes tienen una dedicaci\u00f3n en esta \u00e1rea. Reconocer y realizar diagn\u00f3sticos radiol\u00f3gicos de las diversas anomal\u00edas dentarias y alteraciones de crecimiento y desarrollo maxilofacial.&nbsp;<\/p>\n<p>Formar Profesionales capacitados que logren desarrollar destrezas y competencias en el manejo cl\u00ednico y quir\u00fargico en pacientes que requieran tratamiento integral de mediana y alta complejidad en cirug\u00eda oral.&nbsp;<\/p>\n<p>Dominar las diferentes t\u00e9cnicas exploratorias radiogr\u00e1ficas seg\u00fan las condiciones del paciente y requerimientos cl\u00ednicos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d85faeb elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"1d85faeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-quote\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDescubre la excelencia en Cirug\u00eda Oral con el \nDr. Wilmer Baldarrago\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2faf3940 elementor-widget elementor-widget-heading\" data-id=\"2faf3940\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Contenido acad\u00e9mico<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5f86e279 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5f86e279\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1e3ca843\" data-id=\"1e3ca843\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4cd4189c elementor-widget elementor-widget-text-editor\" data-id=\"4cd4189c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 7\"><div class=\"layoutArea\"><div class=\"column\"><p><span><strong>1.<\/strong> Medicina Estomatolo\u0301gica y Patologi\u0301a Bucomaxilo facial.<br \/><\/span><\/p><p><span><strong>2.<\/strong> Manejo del Ca\u0301ncer Bucal.<br \/><\/span><\/p><p><span><strong>3.<\/strong>Dosis modernas y actualizadas de medicar en estomatologi\u0301a.<\/span><\/p><p><span><strong>4.<\/strong> Manejo del Paciente hi\u0301per o hipotiroideo.<\/span><\/p><p><span><strong>5.<\/strong> Manejo del Paciente con cardiopati\u0301as y de alto riesgo. <\/span><\/p><p><span><strong>6.<\/strong> Farmacologi\u0301a de la actividad endocrina.<br \/><\/span><\/p><p><span><strong>7.<\/strong> Corticoides.<br \/><\/span><\/p><p><span><strong>8.<\/strong> Manejo del Paciente diabe\u0301tico.<\/span><\/p><p><span><strong>9.<\/strong> Farmacologi\u0301a de la actividad cardiovascular. <\/span><\/p><p><span><strong>10.<\/strong> Hemosta\u0301ticos.<br \/><\/span><\/p><p><span><strong>11.<\/strong> Antifibrinoliticos.<br \/><\/span><\/p><p><span><strong>12.<\/strong> Manejo odontolo\u0301gico del paciente hipertenso. <\/span><\/p><p><span><strong>13.<\/strong> Fa\u0301rmacos antihipertensivos.<\/span><\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-22a60f5d\" data-id=\"22a60f5d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5352aeca elementor-widget elementor-widget-text-editor\" data-id=\"5352aeca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 7\"><div class=\"layoutArea\"><div class=\"column\"><p><span><strong>14.<\/strong> Aneste\u0301sicos locales generales.<br \/><\/span><\/p><p><span><strong>15.<\/strong> Sedacio\u0301n consiente y anestesia general en estomatologi\u0301a.<br \/><\/span><\/p><p><span><strong>16.<\/strong> Manejo de ansiedad.<br \/><\/span><\/p><p><span><strong>17.<\/strong> Manejo del dolor.<br \/><\/span><\/p><p><span><strong>18.<\/strong> Terapia de rescate del dolor e inflamacio\u0301n.<br \/><\/span><\/p><p><span><strong>19.<\/strong> Manejo de neuralgias del trige\u0301mino.<br \/><\/span><\/p><p><span><strong>20.<\/strong> Manejo de paresias y parestesias.<br \/><\/span><\/p><p><span><strong>21.<\/strong> Manejo de la inflamacio\u0301n, Trismus, Hematoma.<br \/><\/span><\/p><p><span><strong>22.<\/strong> Manejo farmacolo\u0301gico de infecciones de origen ontoge\u0301nico.<br \/><\/span><\/p><p><span><strong>23.<\/strong> Manejo de la Angina de Ludwing.<br \/><\/span><\/p><p><span><strong>24.<\/strong> Manejo de abscesos, celulitis, flemones y osteomielitis en pacientes de alto riesgo. <\/span><\/p><p><span><strong>25.<\/strong> Manejo de complicaciones post quiru\u0301rgicas<\/span><\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-22a84c3 elementor-widget elementor-widget-heading\" data-id=\"22a84c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Instrumental<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fd55155 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd55155\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b2c9b80\" data-id=\"b2c9b80\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eff73e7 elementor-widget elementor-widget-text-editor\" data-id=\"eff73e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Mango de bistur\u00ed #3.\u00a0<\/li><li>Hoja de bistur\u00ed #15.\u00a0<\/li><li>3\u00a0<span style=\"font-size: inherit; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: var( --e-global-typography-text-font-style ); font-weight: var( --e-global-typography-text-font-weight ); letter-spacing: var( --e-global-typography-text-letter-spacing ); text-transform: var( --e-global-typography-text-text-transform );\">Legras.\u00a0<\/span><\/li><li>Separador de Minessota.\u00a0<\/li><li>Separador de Farabeu.\u00a0<\/li><li>Portagujas ramas largas.\u00a0<\/li><li>Pinza de disecci\u00f3n sin u\u00f1a.\u00a0<\/li><li>Pinza de disecci\u00f3n con u\u00f1a.\u00a0<\/li><li>Mosquito curvo.\u00a0<\/li><li>Mosquito recto.\u00a0<\/li><li>3 Botadores rectos, delgado, mediano, grueso.<\/li><li>Tijeras curva y recta.\u00a0<\/li><li>Fresas quir\u00fargica extra larga tronco c\u00f3nica dentada.\u00a0<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3a2910c\" data-id=\"3a2910c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83fcc2a elementor-widget elementor-widget-text-editor\" data-id=\"83fcc2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>C\u00e1nula de succi\u00f3n met\u00e1lica.\u00a0<\/li><li>Cureta para hueso.\u00a0<\/li><li>Lima para hueso.\u00a0<\/li><li>Pinza gubia.\u00a0<\/li><li>Campos quir\u00fargicos fenestrados (3).\u00a0<\/li><li>Campos quir\u00fargicos cuadrados (3).\u00a0<\/li><li>Tr\u00edpode (espejo, pinza, explorador)\u00a0<\/li><li>Cureta para dentina.\u00a0<\/li><li>Pieza de alta velocidad.\u00a0<\/li><li>Micromotor y fresas quir\u00fargicas para Micromotor.\u00a0<\/li><li>3 Pinzas de campo.\u00a0<\/li><li>Jeringa de uso dental o carpule<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-18110ef elementor-widget elementor-widget-heading\" data-id=\"18110ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Metodolog\u00eda<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b9814c elementor-widget elementor-widget-text-editor\" data-id=\"4b9814c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li><strong>METODOLOG\u00cdA:<\/strong> Te\u00f3rico, pr\u00e1ctico y cl\u00ednico.<\/li>\n<li><strong>CR\u00c9DITOS ACAD\u00c9MICOS:<\/strong> 24 Cr\u00e9ditos.<\/li>\n<li><strong>HORAS ACAD\u00c9MICAS:<\/strong> 384 hrs.<\/li>\n<li><strong>HORARIO:<\/strong> 08:00 &#8211; 16:00 hrs.<\/li>\n<li><strong>DURACI\u00d3N:<\/strong>&nbsp;5 M\u00f3dulos<em>.<\/em><\/li>\n<li><strong>INVERSI\u00d3N:<\/strong> S\/.380.00 por m\u00f3dulo.<\/li>\n<li><strong style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size ); font-style: var( --e-global-typography-text-font-style ); letter-spacing: var( --e-global-typography-text-letter-spacing ); text-transform: var( --e-global-typography-text-text-transform ); text-decoration: var( --e-global-typography-text-text-decoration );\">SEPARACI\u00d3N DE VACANTES:<\/strong><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size ); font-style: var( --e-global-typography-text-font-style ); letter-spacing: var( --e-global-typography-text-letter-spacing ); text-transform: var( --e-global-typography-text-text-transform ); text-decoration: var( --e-global-typography-text-text-decoration );\"> S\/ 150.00 soles.<\/span><\/li>\n<li><strong>AUSPICIO:<\/strong> 10% de descuento al monto total.<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0e43f8 elementor-align-center elementor-widget elementor-widget-elementskit-button\" data-id=\"e0e43f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"http:\/\/masterclassodontologia.com.pe\/wp-content\/uploads\/2024\/07\/Broschure-Cirugia-Oral-Dr-Baldarrah.pdf\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\tDESCARGAR BROSCHURE\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-660544c6 elementor-widget elementor-widget-heading\" data-id=\"660544c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Certif\u00edcate con los mejores<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1a4122 elementor-widget elementor-widget-image\" data-id=\"d1a4122\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img data-opt-id=969883805  data-opt-src=\"https:\/\/mluirrmr33wv.i.optimole.com\/w:822\/h:526\/q:mauto\/ig:avif\/https:\/\/masterclassodontologia.com.pe\/wp-content\/uploads\/2024\/04\/Certificado_MasterClass.jpeg\"  decoding=\"async\" width=\"822\" height=\"526\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%20822%20526%22%20width%3D%22822%22%20height%3D%22526%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%22822%22%20height%3D%22526%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" class=\"attachment-full size-full wp-image-1745\" alt=\"\" old-srcset=\"https:\/\/mluirrmr33wv.i.optimole.com\/w:822\/h:526\/q:mauto\/ig:avif\/https:\/\/masterclassodontologia.com.pe\/wp-content\/uploads\/2024\/04\/Certificado_MasterClass.jpeg 822w, https:\/\/mluirrmr33wv.i.optimole.com\/w:300\/h:192\/q:mauto\/ig:avif\/https:\/\/masterclassodontologia.com.pe\/wp-content\/uploads\/2024\/04\/Certificado_MasterClass.jpeg 300w, https:\/\/mluirrmr33wv.i.optimole.com\/w:768\/h:491\/q:mauto\/ig:avif\/https:\/\/masterclassodontologia.com.pe\/wp-content\/uploads\/2024\/04\/Certificado_MasterClass.jpeg 768w\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4606c3f elementor-widget elementor-widget-image\" data-id=\"4606c3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img data-opt-id=1950705660  data-opt-src=\"https:\/\/mluirrmr33wv.i.optimole.com\/w:840\/h:595\/q:mauto\/ig:avif\/https:\/\/masterclassodontologia.com.pe\/wp-content\/uploads\/2024\/04\/Certificado_LaSalle.jpeg\"  decoding=\"async\" width=\"840\" height=\"595\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%20840%20595%22%20width%3D%22840%22%20height%3D%22595%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%22840%22%20height%3D%22595%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" class=\"attachment-full size-full wp-image-1744\" alt=\"\" old-srcset=\"https:\/\/mluirrmr33wv.i.optimole.com\/w:840\/h:595\/q:mauto\/ig:avif\/https:\/\/masterclassodontologia.com.pe\/wp-content\/uploads\/2024\/04\/Certificado_LaSalle.jpeg 840w, https:\/\/mluirrmr33wv.i.optimole.com\/w:300\/h:213\/q:mauto\/ig:avif\/https:\/\/masterclassodontologia.com.pe\/wp-content\/uploads\/2024\/04\/Certificado_LaSalle.jpeg 300w, https:\/\/mluirrmr33wv.i.optimole.com\/w:768\/h:544\/q:mauto\/ig:avif\/https:\/\/masterclassodontologia.com.pe\/wp-content\/uploads\/2024\/04\/Certificado_LaSalle.jpeg 768w\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63cd7ec ekit-equal-height-disable elementor-widget elementor-widget-elementskit-image-box\" data-id=\"63cd7ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n            <div class=\"elementskit-info-image-box ekit-image-box text-center simple-card\" >\n\n                \n                <div class=\"elementskit-box-header image-box-img-center\">\n\n                    \n                <\/div>\n                \n                <div class=\"elementskit-box-body ekit-image-box-body\">\n                    <div class=\"elementskit-box-content ekit-image-box-body-inner\">\n                                                <h3 class=\"elementskit-info-box-title\">\n\n                        Auspicio Nacional e Internacional\n                        \n                    <\/h3>\n                                                            <div class=\"elementskit-box-style-content\">\n                        Todos nuestros estudiantes cuentan con la posibilidad de a\u00f1adir un certificado adicional bajo el auspicio acad\u00e9mico nacional e internacional.                    <\/div>\n                                    <\/div>\n\n                            <\/div>\n            <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b09b850 elementor-align-center elementor-widget elementor-widget-elementskit-button\" data-id=\"b09b850\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/api.whatsapp.com\/send\/?phone=941774399&#038;text&#038;type=phone_number&#038;app_absent=0\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\t<i class=\"icon icon-whatsapp-1\"><\/i>SEPARA TU VACANTE\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-77232a45\" data-id=\"77232a45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2aa6261d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2aa6261d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-11c9e8da\" data-id=\"11c9e8da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b9bd9d5 elementor-widget elementor-widget-heading\" data-id=\"3b9bd9d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00daltimas Noticias<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4be6c810 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4be6c810\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a292a78 elementor-widget elementor-widget-elementskit-post-list\" data-id=\"4a292a78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-post-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<ul class=\"elementor-icon-list-items ekit-post-list-wrapper \">\n\t\t\t\t\t\t<li class=\"elementor-icon-list-item   \">\n\t\t\t\t<a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/2023\/12\/10\/nuevas-tecnicas-en-odontologia-estetica\/\" >\n\t\t\t\t\t\t\t\t\t\t<div class=\"ekit_post_list_content_wraper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"meta-lists\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"meta-date\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t10 Dic 2023\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Nuevas t\u00e9cnicas en odontolog\u00eda est\u00e9tica<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t<li class=\"elementor-icon-list-item   \">\n\t\t\t\t<a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/2023\/07\/28\/descubre-el-poder-de-la-capacitacion-en-odontologia-con-masterclass\/\" >\n\t\t\t\t\t\t\t\t\t\t<div class=\"ekit_post_list_content_wraper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"meta-lists\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"meta-date\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t28 Jul 2023\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00a1Descubre el poder de la capacitaci\u00f3n en odontolog\u00eda con MasterClass!<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-62c18a33 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62c18a33\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6dd658e\" data-id=\"6dd658e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2221fe6b elementor-widget elementor-widget-heading\" data-id=\"2221fe6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Te puede interesar<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c0eb8f1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5c0eb8f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eaad35d elementor-grid-1 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-loop-grid\" data-id=\"eaad35d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:&quot;1140&quot;,&quot;columns&quot;:1,&quot;_skin&quot;:&quot;post&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;[data-elementor-type=\\&quot;loop-item\\&quot;]&quot;,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-grid.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-loop-container elementor-grid\">\n\t\t<style id=\"loop-1140\">.elementor-1140 .elementor-element.elementor-element-b93ddde .elementor-menu-toggle{margin:0 auto;}.elementor-1140 .elementor-element.elementor-element-b93ddde .elementor-nav-menu .elementor-item{font-family:\"Sora\", Sans-serif;font-size:14px;font-weight:400;line-height:11px;letter-spacing:0px;word-spacing:0px;}.elementor-1140 .elementor-element.elementor-element-b93ddde .elementor-nav-menu--main .elementor-item{padding-top:10px;padding-bottom:10px;}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"1140\" class=\"elementor elementor-1140 e-loop-item e-loop-item-783 post-783 post type-post status-publish format-standard hentry category-masterclass\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-140bfe8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"140bfe8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-866ad0e\" data-id=\"866ad0e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-69e9db8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69e9db8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-47074a6\" data-id=\"47074a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b93ddde elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"b93ddde\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-b93ddde\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1157\"><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/cirugia-oral\/\" class=\"elementor-item\">Cirug\u00eda Oral<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1158\"><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/endodoncia\/\" class=\"elementor-item\">Endodoncia<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1159\"><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/farmacologia-y-medicina-estomatologica\/\" class=\"elementor-item\">Farmacolog\u00eda y Medicina Estomatol\u00f3gica<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1160\"><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/odontologia-estetica-y-restauradora\/\" class=\"elementor-item\">Odontolog\u00eda Est\u00e9tica y Restauradora<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1162\"><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/ortodoncia-y-ortopedia-maxilofacial\/\" class=\"elementor-item\">Ortodoncia y Ortopedia Maxilofacial<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1165\"><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/inmersion-en-odontologia-para-pacientes-con-compromiso-sistemico\/\" class=\"elementor-item\">Inmersi\u00f3n en Odontolog\u00eda para Pacientes con Compromiso Sist\u00e9mico\u00a0<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1368\"><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/implantologia\/\" class=\"elementor-item\">Implantolog\u00eda<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-b93ddde\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1157\"><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/cirugia-oral\/\" class=\"elementor-item\" tabindex=\"-1\">Cirug\u00eda Oral<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1158\"><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/endodoncia\/\" class=\"elementor-item\" tabindex=\"-1\">Endodoncia<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1159\"><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/farmacologia-y-medicina-estomatologica\/\" class=\"elementor-item\" tabindex=\"-1\">Farmacolog\u00eda y Medicina Estomatol\u00f3gica<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1160\"><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/odontologia-estetica-y-restauradora\/\" class=\"elementor-item\" tabindex=\"-1\">Odontolog\u00eda Est\u00e9tica y Restauradora<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1162\"><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/ortodoncia-y-ortopedia-maxilofacial\/\" class=\"elementor-item\" tabindex=\"-1\">Ortodoncia y Ortopedia Maxilofacial<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1165\"><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/inmersion-en-odontologia-para-pacientes-con-compromiso-sistemico\/\" class=\"elementor-item\" tabindex=\"-1\">Inmersi\u00f3n en Odontolog\u00eda para Pacientes con Compromiso Sist\u00e9mico\u00a0<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1368\"><a href=\"https:\/\/masterclassodontologia.com.pe\/index.php\/implantologia\/\" class=\"elementor-item\" tabindex=\"-1\">Implantolog\u00eda<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4486a258 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4486a258\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-bdf0773\" data-id=\"bdf0773\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-670e40c3 elementor-widget elementor-widget-heading\" data-id=\"670e40c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfNecesitas ayuda?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca3067c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ca3067c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fa08348 elementor-widget elementor-widget-text-editor\" data-id=\"5fa08348\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si necesitas una atenci\u00f3n personalizada no dudes en ponerte en contacto con nosotros<\/p><p>Pregunta por nuestros descuentos corporativos por inscripciones grupales.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a7e49df elementor-align-center elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"3a7e49df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/api.whatsapp.com\/send\/?phone=941774399&#038;text&#038;type=phone_number&#038;app_absent=0\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Escr\u00edbenos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3abb8a94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3abb8a94\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-edb92f9\" data-id=\"edb92f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1eddbe98 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1eddbe98\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-41e80401\" data-id=\"41e80401\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bddf6d8 elementor-widget elementor-widget-image\" data-id=\"5bddf6d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img data-opt-id=1198196302  data-opt-src=\"https:\/\/mluirrmr33wv.i.optimole.com\/w:1011\/h:268\/q:mauto\/ig:avif\/https:\/\/masterclassodontologia.com.pe\/wp-content\/uploads\/2024\/02\/NewLogo_MC.png\"  loading=\"lazy\" decoding=\"async\" width=\"1011\" height=\"268\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%201011%20268%22%20width%3D%221011%22%20height%3D%22268%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%221011%22%20height%3D%22268%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" class=\"attachment-full size-full wp-image-1319\" alt=\"\" old-srcset=\"https:\/\/mluirrmr33wv.i.optimole.com\/w:1011\/h:268\/q:mauto\/ig:avif\/https:\/\/masterclassodontologia.com.pe\/wp-content\/uploads\/2024\/02\/NewLogo_MC.png 1011w, https:\/\/mluirrmr33wv.i.optimole.com\/w:300\/h:80\/q:mauto\/ig:avif\/https:\/\/masterclassodontologia.com.pe\/wp-content\/uploads\/2024\/02\/NewLogo_MC.png 300w, https:\/\/mluirrmr33wv.i.optimole.com\/w:768\/h:204\/q:mauto\/ig:avif\/https:\/\/masterclassodontologia.com.pe\/wp-content\/uploads\/2024\/02\/NewLogo_MC.png 768w\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3138dd44 elementor-widget elementor-widget-text-editor\" data-id=\"3138dd44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"caret-color: #ffffff;\">Educaci\u00f3n continua para la especializaci\u00f3n de profesionales en odontolog\u00eda.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-589c2311 elementor-shape-circle e-grid-align-left e-grid-align-mobile-center e-grid-align-tablet-center elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"589c2311\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-repeater-item-f27eb82\" href=\"https:\/\/www.facebook.com\/masterclass.aqp\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-4067d8b\" href=\"https:\/\/www.instagram.com\/masterclass.arequipa\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-whatsapp elementor-repeater-item-f172d08\" href=\"https:\/\/api.whatsapp.com\/send\/?phone=941774399&#038;text&#038;type=phone_number&#038;app_absent=0\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Whatsapp<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-45c1be41\" data-id=\"45c1be41\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e1320bd elementor-widget elementor-widget-heading\" data-id=\"7e1320bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Encu\u00e9ntranos<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36fe5a2a elementor-widget elementor-widget-elementskit-header-info\" data-id=\"36fe5a2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-header-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <ul class=\"ekit-header-info\">\n                                    <li>\n                            <a href=\"https:\/\/maps.app.goo.gl\/81uCBhh6zNBpvo6u5\" target=\"_blank\" rel=\"nofollow\"> \n                                                                Av. Independencia 1900, Cercado - Arequipa, Per\u00fa.                            <\/a>\n                        <\/li>\n\n                            <\/ul>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66fcef67 elementor-widget elementor-widget-elementskit-header-info\" data-id=\"66fcef67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-header-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <ul class=\"ekit-header-info\">\n                                    <li>\n                            <a href=\"#\" target=\"_blank\" rel=\"nofollow\"> \n                                                                08.00 AM - 17.00 PM                            <\/a>\n                        <\/li>\n\n                            <\/ul>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12579b3b elementor-widget elementor-widget-heading\" data-id=\"12579b3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Cont\u00e1ctanos<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-290ecf6e elementor-widget elementor-widget-elementskit-header-info\" data-id=\"290ecf6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-header-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <ul class=\"ekit-header-info\">\n                                    <li>\n                            <a href=\"https:\/\/api.whatsapp.com\/send\/?phone=941774399&#038;text&#038;type=phone_number&#038;app_absent=0\" target=\"_blank\" rel=\"nofollow\"> \n                                                                +51 941 774 399                            <\/a>\n                        <\/li>\n\n                            <\/ul>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f175389 elementor-widget elementor-widget-elementskit-header-info\" data-id=\"7f175389\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-header-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <ul class=\"ekit-header-info\">\n                                    <li>\n                            <a href=\"http:\/\/contacto@masterclassodontologia.com.pe\" target=\"_blank\" rel=\"nofollow\"> \n                                                                contacto@masterclassodontologia.com.pe                            <\/a>\n                        <\/li>\n\n                            <\/ul>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1197b34f\" data-id=\"1197b34f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ea40aec elementor-widget elementor-widget-heading\" data-id=\"2ea40aec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Legal<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f1551bd elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2f1551bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Auspicio acad\u00e9mico<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Reglamento<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">FAQs<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-36b8b9cb elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"36b8b9cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5a46c33e\" data-id=\"5a46c33e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d8711ba elementor-widget elementor-widget-text-editor\" data-id=\"3d8711ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Copyright \u00a9 2022 Personalizado por Indpndnt Std. 2023<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-63756d87\" data-id=\"63756d87\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4dd68caa elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"4dd68caa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Pol\u00edtica de Privacidad<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ad0b43b elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"7ad0b43b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">T\u00e9rminos y Condiciones<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-992afff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"992afff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ab02d7\" data-id=\"7ab02d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Inicio Diplomados Endodoncia Odontopediatr\u00eda Cirug\u00eda Oral Implantolog\u00eda Oral Ortodoncia y Ortopedia Maxilofacial Odontolog\u00eda Est\u00e9tica y Restauradora Cursos Restauraciones Semidirectas de Resinas Compuestas Actualizaci\u00f3n Cirug\u00eda Paraendod\u00f3ntica 2024 Aula Virtual Blog X Cont\u00e1ctanos Cirug\u00eda Oral El objetivo del Diplomado en Cirug\u00eda Oral brinda los conocimientos y competencias para mejorar la calidad de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-490","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/masterclassodontologia.com.pe\/index.php\/wp-json\/wp\/v2\/pages\/490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/masterclassodontologia.com.pe\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/masterclassodontologia.com.pe\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/masterclassodontologia.com.pe\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/masterclassodontologia.com.pe\/index.php\/wp-json\/wp\/v2\/comments?post=490"}],"version-history":[{"count":189,"href":"https:\/\/masterclassodontologia.com.pe\/index.php\/wp-json\/wp\/v2\/pages\/490\/revisions"}],"predecessor-version":[{"id":2164,"href":"https:\/\/masterclassodontologia.com.pe\/index.php\/wp-json\/wp\/v2\/pages\/490\/revisions\/2164"}],"wp:attachment":[{"href":"https:\/\/masterclassodontologia.com.pe\/index.php\/wp-json\/wp\/v2\/media?parent=490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}